{"id":14578,"date":"2020-06-05T18:16:31","date_gmt":"2020-06-05T23:16:31","guid":{"rendered":"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi.jpg"},"modified":"2023-02-19T13:11:10","modified_gmt":"2023-02-19T18:11:10","slug":"glaciar-volcan-cotopaxi-2","status":"inherit","type":"attachment","link":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/","title":{"rendered":"Glacier du volcan Cotopaxi"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":""},"class_list":["post-14578","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l&#039;ann\u00e9e\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"adrian\"\/>\n\t<meta name=\"google-site-verification\" content=\"googlef937a053ee54e51c.html\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Living Ecuador Travel\" \/>\n\t\t<meta property=\"og:type\" content=\"country\" \/>\n\t\t<meta property=\"og:title\" content=\"Glacier du volcan Cotopaxi | Living Ecuador Travel\" \/>\n\t\t<meta property=\"og:description\" content=\"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l&#039;ann\u00e9e\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"2920942451323191\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1967070186706250\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Glacier du volcan Cotopaxi | Living Ecuador Travel\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l&#039;ann\u00e9e\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#listItem\",\"name\":\"Glacier du volcan Cotopaxi\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#listItem\",\"position\":2,\"name\":\"Glacier du volcan Cotopaxi\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#itempage\",\"url\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/\",\"name\":\"Glacier du volcan Cotopaxi | Living Ecuador Travel\",\"description\":\"Le glacier du volcan Cotopaxi peut \\u00eatre visit\\u00e9 toute l'ann\\u00e9e\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/author\\\/adrian\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/author\\\/adrian\\\/#author\"},\"datePublished\":\"2020-06-05T18:16:31-05:00\",\"dateModified\":\"2023-02-19T13:11:10-05:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#organization\",\"name\":\"Living Ecuador Travel\",\"description\":\"Agencia de viajes receptiva en Ecuador\",\"url\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LivingEcuadorTravel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/livingecuadortravel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/author\\\/adrian\\\/#author\",\"url\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/author\\\/adrian\\\/\",\"name\":\"adrian\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/glaciar-volcan-cotopaxi-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca4ded340338aa8edbf153b68d942c5d27261a98103f95d8e279b505df457c90?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"adrian\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/\",\"name\":\"Living Ecuador Travel\",\"description\":\"Agencia de viajes receptiva en Ecuador\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingecuadortravel.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Glacier du volcan Cotopaxi | Living Ecuador Travel","description":"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l'ann\u00e9e","canonical_url":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"googlef937a053ee54e51c.html","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/livingecuadortravel.com\/fr\/#listItem","position":1,"name":"Inicio","item":"https:\/\/livingecuadortravel.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#listItem","name":"Glacier du volcan Cotopaxi"}},{"@type":"ListItem","@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#listItem","position":2,"name":"Glacier du volcan Cotopaxi","previousItem":{"@type":"ListItem","@id":"https:\/\/livingecuadortravel.com\/fr\/#listItem","name":"Inicio"}}]},{"@type":"ItemPage","@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#itempage","url":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/","name":"Glacier du volcan Cotopaxi | Living Ecuador Travel","description":"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l'ann\u00e9e","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/livingecuadortravel.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#breadcrumblist"},"author":{"@id":"https:\/\/livingecuadortravel.com\/fr\/author\/adrian\/#author"},"creator":{"@id":"https:\/\/livingecuadortravel.com\/fr\/author\/adrian\/#author"},"datePublished":"2020-06-05T18:16:31-05:00","dateModified":"2023-02-19T13:11:10-05:00"},{"@type":"Organization","@id":"https:\/\/livingecuadortravel.com\/fr\/#organization","name":"Living Ecuador Travel","description":"Agencia de viajes receptiva en Ecuador","url":"https:\/\/livingecuadortravel.com\/fr\/","sameAs":["https:\/\/www.facebook.com\/LivingEcuadorTravel\/","https:\/\/www.instagram.com\/livingecuadortravel\/"]},{"@type":"Person","@id":"https:\/\/livingecuadortravel.com\/fr\/author\/adrian\/#author","url":"https:\/\/livingecuadortravel.com\/fr\/author\/adrian\/","name":"adrian","image":{"@type":"ImageObject","@id":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ca4ded340338aa8edbf153b68d942c5d27261a98103f95d8e279b505df457c90?s=96&d=mm&r=g","width":96,"height":96,"caption":"adrian"}},{"@type":"WebSite","@id":"https:\/\/livingecuadortravel.com\/fr\/#website","url":"https:\/\/livingecuadortravel.com\/fr\/","name":"Living Ecuador Travel","description":"Agencia de viajes receptiva en Ecuador","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/livingecuadortravel.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Living Ecuador Travel","og:type":"country","og:title":"Glacier du volcan Cotopaxi | Living Ecuador Travel","og:description":"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l'ann\u00e9e","og:url":"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/","fb:app_id":"2920942451323191","fb:admins":"1967070186706250","og:image":"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg","og:image:secure_url":"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg","twitter:card":"summary","twitter:title":"Glacier du volcan Cotopaxi | Living Ecuador Travel","twitter:description":"Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l'ann\u00e9e","twitter:image":"https:\/\/www.livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Senderismo-en-el-volcan-Cotopaxi.jpg"},"aioseo_meta_data":{"post_id":"14578","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-02 17:04:47","updated":"2025-07-04 22:11:07","seo_analyzer_scan_date":null},"smush":"Not processed","description":{"rendered":"<a data-toggle=\"lightbox\" data-gallery=\"multiimages\" data-title=\"Randonn\u00e9e glaciaire Cotopaxi\"  class=\"thumbnail img-thumbnail\" href='https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-743x950.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"743\" height=\"950\" src=\"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-743x950.jpg\" class=\"attachment-th_img_xl size-th_img_xl\" alt=\"Randonn\u00e9e glaciaire Cotopaxi\" srcset=\"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-743x950.jpg 743w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-235x300.jpg 235w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-801x1024.jpg 801w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-768x981.jpg 768w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-1202x1536.jpg 1202w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-31x40.jpg 31w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-63x80.jpg 63w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-237x303.jpg 237w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-548x700.jpg 548w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-845x1080.jpg 845w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-600x767.jpg 600w, https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-743x950.jpg 1440w\" sizes=\"(max-width: 743px) 100vw, 743px\" \/><\/a>\n<p>El glaciar del volcan Cotopaxi se enciuentra a m\u00e1s de 4800 m y se puede acceder de manera controlada desde el refugio<\/p>\n"},"caption":{"rendered":"<p>Le glacier du volcan Cotopaxi peut \u00eatre visit\u00e9 toute l&rsquo;ann\u00e9e &hellip; <a href=\"https:\/\/livingecuadortravel.com\/fr\/glaciar-volcan-cotopaxi-2\/\">Read More<\/a><\/p>\n"},"alt_text":"Randonn\u00e9e glaciaire Cotopaxi","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1440,"height":1840,"file":"2020\/03\/Glaciar-volcan-Cotopaxi.jpg","sizes":{"medium":{"file":"Glaciar-volcan-Cotopaxi-235x300.jpg","width":235,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-235x300.jpg"},"large":{"file":"Glaciar-volcan-Cotopaxi-801x1024.jpg","width":801,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-801x1024.jpg"},"thumbnail":{"file":"Glaciar-volcan-Cotopaxi-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-150x150.jpg"},"medium_large":{"file":"Glaciar-volcan-Cotopaxi-768x981.jpg","width":768,"height":981,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-768x981.jpg"},"1536x1536":{"file":"Glaciar-volcan-Cotopaxi-1202x1536.jpg","width":1202,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-1202x1536.jpg"},"themo-logo":{"file":"Glaciar-volcan-Cotopaxi-31x40.jpg","width":31,"height":40,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-31x40.jpg"},"th_img_xs":{"file":"Glaciar-volcan-Cotopaxi-63x80.jpg","width":63,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-63x80.jpg"},"th_img_sm_landscape":{"file":"Glaciar-volcan-Cotopaxi-394x303.jpg","width":394,"height":303,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-394x303.jpg"},"th_img_sm_portrait":{"file":"Glaciar-volcan-Cotopaxi-394x512.jpg","width":394,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-394x512.jpg"},"th_img_sm_square":{"file":"Glaciar-volcan-Cotopaxi-394x394.jpg","width":394,"height":394,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-394x394.jpg"},"th_img_sm_standard":{"file":"Glaciar-volcan-Cotopaxi-237x303.jpg","width":237,"height":303,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-237x303.jpg"},"th_img_md_landscape":{"file":"Glaciar-volcan-Cotopaxi-605x465.jpg","width":605,"height":465,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-605x465.jpg"},"th_img_md_portrait":{"file":"Glaciar-volcan-Cotopaxi-605x806.jpg","width":605,"height":806,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-605x806.jpg"},"th_img_md_square":{"file":"Glaciar-volcan-Cotopaxi-605x605.jpg","width":605,"height":605,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-605x605.jpg"},"th_img_lg":{"file":"Glaciar-volcan-Cotopaxi-548x700.jpg","width":548,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-548x700.jpg"},"th_img_xl":{"file":"Glaciar-volcan-Cotopaxi-743x950.jpg","width":743,"height":950,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-743x950.jpg"},"th_img_xxl":{"file":"Glaciar-volcan-Cotopaxi-845x1080.jpg","width":845,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-845x1080.jpg"},"woocommerce_thumbnail":{"file":"Glaciar-volcan-Cotopaxi-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-300x300.jpg"},"woocommerce_single":{"file":"Glaciar-volcan-Cotopaxi-600x767.jpg","width":600,"height":767,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-600x767.jpg"},"woocommerce_gallery_thumbnail":{"file":"Glaciar-volcan-Cotopaxi-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-100x100.jpg"},"shop_catalog":{"file":"Glaciar-volcan-Cotopaxi-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-300x300.jpg"},"shop_single":{"file":"Glaciar-volcan-Cotopaxi-600x767.jpg","width":600,"height":767,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-600x767.jpg"},"shop_thumbnail":{"file":"Glaciar-volcan-Cotopaxi-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi-100x100.jpg"},"full":{"file":"Glaciar-volcan-Cotopaxi.jpg","width":1440,"height":1840,"mime_type":"image\/jpeg","source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"Glaciar volcan Cotopaxi","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"Glaciar volcan Cotopaxi","orientation":"0","keywords":["Trekking, cotopaxi, volcanes"]}},"post":null,"source_url":"https:\/\/livingecuadortravel.com\/wp-content\/uploads\/2020\/03\/Glaciar-volcan-Cotopaxi.jpg","filename":"Glaciar-volcan-Cotopaxi.jpg","filesize":794196,"_links":{"self":[{"href":"https:\/\/livingecuadortravel.com\/fr\/wp-json\/wp\/v2\/media\/14578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingecuadortravel.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/livingecuadortravel.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/livingecuadortravel.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/livingecuadortravel.com\/fr\/wp-json\/wp\/v2\/comments?post=14578"}]}}